{"id":5252,"date":"2021-08-20T06:58:40","date_gmt":"2021-08-20T03:58:40","guid":{"rendered":"https:\/\/flags-world.com\/it\/2021\/08\/20\/bandiera-coreana-significato-e-colori\/"},"modified":"2021-08-20T06:58:40","modified_gmt":"2021-08-20T03:58:40","slug":"bandiera-coreana-significato-e-colori","status":"publish","type":"post","link":"https:\/\/flags-world.com\/it\/bandiera-coreana-significato-e-colori\/","title":{"rendered":"Bandiera coreana: significato e colori"},"content":{"rendered":"<p style=\"text-align: justify\">La Corea del Sud \u00e8 conosciuta in tutto il mondo con i suoi chirurghi plastici, elettronica e musica. La bandiera della Corea ha ricevuto ampia fama tra coloro che sono interessati alla storia del paese, alla sua cultura. \u00c8 usato per designare lo stato in tutti gli eventi ufficiali. La messa in scena coreana ha una lunga storia e ha una connessione con un altro stato esistente nel nostro tempo. Questo rende pi\u00f9 interessante il suo studio e la sua decrittazione, permette di conoscere meglio le peculiarit\u00e0 delle persone.<\/p>\n<h2 style=\"text-align: justify\">Bandiera della Corea del Sud: foto<\/h2>\n<p style=\"text-align: justify\">L&apos;aspetto della bandiera coreana pu\u00f2 essere visto nella foto qui sotto.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5254\" src=\"\/wp-content\/uploads\/2021\/08\/korean-flag_1.png\" width=\"500\" height=\"333\" alt=\"Bandiera della Corea\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"333\"><\/span><\/p>\n<p style=\"text-align: justify\">Il simbolismo di stato si basa sullo stendardo del Times of Choson e dell&apos;Impero coreano, sebbene abbia piccole differenze. Gli eventi storici del periodo Coson sono spesso evidenziati nella letteratura artistica del paese, nei suoi programmi televisivi (compresi i melodrammi storici). Di particolare importanza sono i simboli posti su un panno bianco. La versione moderna dello Standard \u00e8 stata l&apos;ultima volta che \u00e8 stata modificata nel 2011.<\/p>\n<h2 style=\"text-align: justify\">Il significato colora la bandiera della Corea del Sud<\/h2>\n<p style=\"text-align: justify\">L&apos;attuale bandiera della Repubblica di Corea ha il seguente significato:<\/p>\n<ol style=\"text-align: justify\">\n<li>Il colore bianco della tela \u00e8 un richiamo alle tradizioni dello stato. Denota la purezza degli ideali;<\/li>\n<li>Il simbolo situato al centro dello Steag significa gli inizi opposti di Yin e Yang. Yin &#8211; blu, yang &#8211; rosso;<\/li>\n<li>Il colore nero di un trigramma, situato negli angoli attorno al simbolo centrale, \u00e8 selezionato per il trasferimento della vigilanza, della resistenza, della castit\u00e0 del popolo coreano;<\/li>\n<li>I trigrammi sono costituiti da yin e yang (sono indicati rispettivamente da strisce strappate e solide). Ogni trigramma ha 4 valori. Denotano le stagioni, i principali corpi celesti, le parti del mondo e i quattro elementi principali (acqua, aria, terra, fuoco).<\/li>\n<\/ol>\n<blockquote>\n<p style=\"text-align: justify\">I trigrammi vengono letti dall&apos;angolo in alto a sinistra in senso orario.<\/p>\n<\/blockquote>\n<h2 style=\"text-align: justify\">Che aspetto ha la bandiera coreana<\/h2>\n<p style=\"text-align: justify\">Per fotografia puoi comporre la seguente descrizione della bandiera della Repubblica di Corea:<\/p>\n<ul style=\"text-align: justify\">\n<li>La tela di forma rettangolare, con bordi lisci, senza bordatura e iscrizioni;<\/li>\n<li>Al centro &#8211; il cerchio a due colori (usati i colori rosso e blu) composto da caratteri Yin e Yang;<\/li>\n<li>Vicino agli angoli intorno agli angoli, ci sono quattro trigrammi neri.<\/li>\n<\/ul>\n<blockquote>\n<p style=\"text-align: justify\">Stog ripetutamente soggetto a modifiche. La dimensione dei trigrammi \u00e8 cambiata e il colore, la distanza tra le strisce al loro interno, le sfumature utilizzate per il cerchio centrale.<\/p>\n<\/blockquote>\n<h2 style=\"text-align: justify\">Bandiere della Corea prima della separazione<\/h2>\n<p style=\"text-align: justify\">Fino al 1945 lo stato era unito. Dopo la sconfitta del Giappone nella seconda guerra mondiale, il suo territorio fu diviso in due zone per le quali la responsabilit\u00e0 dell&apos;URSS e degli Stati Uniti.<\/p>\n<p style=\"text-align: justify\">Nel 1948, dopo la separazione, queste zone si trasformarono in due stati separati con il loro simbolismo. Come la bandiera della Repubblica di Corea, \u00e8 stata utilizzata una &quot;Thagikeki&quot; modificata, la seconda repubblica sotto l&apos;influenza della democrazia e del socialismo ha sviluppato il proprio simbolismo. Prima della separazione degli stati nel territorio coreano, c&apos;erano due opzioni per lo Stendardo Nazionale.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5255\" src=\"\/wp-content\/uploads\/2021\/08\/korean-flag_1.jpg\" alt=\"Bandiera della Corea del Sud\" width=\"500\" height=\"292\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"292\"><\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify\">Il primo ha agito dal 1883 al 1910 (la foto \u00e8 presentata sopra)<\/p>\n<\/blockquote>\n<h2 style=\"text-align: justify\">Simbolismo coreano 1919-1948<\/h2>\n<p style=\"text-align: justify\">&quot;Thagikeki&quot; pu\u00f2 essere basato su qualsiasi bandiera coreana di quel periodo. Nel periodo dal 1919 al 1948 \u00e8 stata utilizzata una versione modificata dello Stendardo Nazionale. Per vedere come appariva, puoi nella foto qui sotto.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5253\" src=\"\/wp-content\/uploads\/2021\/08\/korean-flag_2.png\" alt=\"Bandiera coreana\" width=\"361\" height=\"240\" \/><meta itemprop=\"width\" content=\"361\"><meta itemprop=\"height\" content=\"240\"><\/span><\/p>\n<p style=\"text-align: justify\">Una variazione moderna \u00e8 caratterizzata dall&apos;uso di tonalit\u00e0 pi\u00f9 luminose. Modificata la posizione dei caratteri Yin e Yang: nella versione del 1919, sono posizionati verticalmente e non orizzontalmente.<\/p>\n<blockquote>\n<p style=\"text-align: justify\">Le strisce in triangoli nella vecchia versione pi\u00f9 corte, si trovano ad una distanza maggiore l&apos;una dall&apos;altra. Modificato e la loro posizione in senso orario.<\/p>\n<\/blockquote>\n<h2 style=\"text-align: justify\">Bandiera della Repubblica Democratica Popolare Coreana<\/h2>\n<p style=\"text-align: justify\">I simboli vengono periodicamente confusi con la bandiera della Repubblica Democratica Popolare Coreana (RPDC), sebbene esternamente gli stendardi siano diversi. La fotografia Passeggiata nella RPDC \u00e8 presentata di seguito.<\/p>\n<p><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5247\" src=\"\/wp-content\/uploads\/2021\/08\/flag-of-north-korea_1.png\" alt=\"Bandiera della Corea del Nord\" width=\"500\" height=\"250\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"250\"><\/span><\/p>\n<p style=\"text-align: justify\">Le differenze sono serie &#8211; prevale il colore rosso, mancano i simboli di Yin e Yang, cos\u00ec come le rifiniture. Il significato della RPDC \u00e8 diverso: invece delle designazioni filosofiche della natura, maschio e femmina, qui prevale il ricordo dei patrioti morti. Il desiderio di cambiamenti rivoluzionari nella lotta per il socialismo. Il colore bianco \u00e8 presente in minima parte e lasciato in omaggio alla storia e alle tradizioni popolari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Corea del Sud \u00e8 conosciuta in tutto il mondo con i suoi chirurghi plastici, elettronica e musica. La bandiera della Corea ha ricevuto ampia fama tra coloro&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-5252","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-bandiere-asia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/posts\/5252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/comments?post=5252"}],"version-history":[{"count":0,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/posts\/5252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/media\/5802"}],"wp:attachment":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/media?parent=5252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/categories?post=5252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/tags?post=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}