{"id":1562,"date":"2021-01-04T17:18:12","date_gmt":"2021-01-04T14:18:12","guid":{"rendered":"https:\/\/flags-world.com\/it\/2021\/01\/04\/bandiera-iraq-significato-e-storia\/"},"modified":"2021-01-04T17:18:12","modified_gmt":"2021-01-04T14:18:12","slug":"bandiera-iraq-significato-e-storia","status":"publish","type":"post","link":"https:\/\/flags-world.com\/it\/bandiera-iraq-significato-e-storia\/","title":{"rendered":"Bandiera Iraq: significato e storia"},"content":{"rendered":"<p style=\"text-align: justify\">Bandiera dell&apos;Iraq &#8211; uno dei principali segni di statualit\u00e0 di questo paese. La bandiera odierna della Repubblica irachena \u00e8 piuttosto giovane: \u00e8 stata adottata dal Parlamento del Paese nel 2008.<\/p>\n<p style=\"text-align: justify\">Quindi la moderna bandiera dell&apos;Iraq sembra:<\/p>\n<p style=\"text-align: justify\"><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3320\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_1.png\" width=\"500\" height=\"333\" alt=\"Bandiera Iraq-1\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"333\"><\/span><\/p>\n<h2 style=\"text-align: justify\">Bandiera della storia dell&apos;Iraq<\/h2>\n<p style=\"text-align: justify\">In soli 98 anni di indipendenza, l&apos;Iraq ha cambiato 7 bandiere. La prima bandiera dell&apos;Iraq era una tela, come la moderna bandiera giordana: tre strisce dipinte orizzontalmente nei colori nero, bianco e verde con un triangolo rosso sul bordo sinistro.<\/p>\n<p style=\"text-align: justify\"><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3321\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_2.png\" width=\"500\" height=\"250\" alt=\"Bandiera dell&apos;Iraq-2\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"250\"><\/span><\/p>\n<p style=\"text-align: justify\">3 anni dopo (nel 1924), fu sottoposto a modifiche: il triangolo sul lato sinistro della bandiera fu accorciato allo stato di un trapezio geometrico. Nella stessa figura sono state poste due stelle bianche con sette picchi.<\/p>\n<p style=\"text-align: justify\"><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3322\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_3.png\" width=\"500\" height=\"250\" alt=\"Bandiera dell&apos;Iraq-3\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"250\"><\/span><\/p>\n<p style=\"text-align: justify\">In questa forma, la bandiera esisteva da 35 anni. Nella seconda met\u00e0 degli anni &apos;50 del XX secolo, in Iraq avvenne una rivolta armata che la famiglia monarchica governata. Ci\u00f2 si \u00e8 riflesso nella bandiera comunale, che \u00e8 apparsa in un aspetto nuovissimo: ora \u00e8 stata piegata da tre strisce verticali, verniciate rispettivamente nei colori nero, bianco e verde. Sulla striscia centrale di bianco, senza contare questa c&apos;era una figura rossa sotto forma di un luccichio con sette vertici e un cerchio giallo al centro. Tale il sole \u00e8 stato aggiunto alla bandiera non proprio cos\u00ec &#8211; il colore giallo significava la popolazione curda dell&apos;Ucraina, e il rosso &#8211; il popolo assiro di questo paese.<\/p>\n<p style=\"text-align: justify\"><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3323\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_4.png\" width=\"500\" height=\"250\" alt=\"Bandiera dell&apos;Iraq-4\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"250\"><\/span><\/p>\n<p style=\"text-align: justify\">Ma questa bandiera \u00e8 rimasta il segno dell&apos;Iraq per un breve periodo &#8211; dopo 4 anni nel paese, \u00e8 successo di nuovo un colpo di stato dell&apos;esercito. La nuova bandiera comunale era una tela, che si apriva su tre corsie di colori successivi: rosso, bianco e nero. Erano uguali e posizionati orizzontalmente. Al centro della bandiera erano disposte tre stelle verdi. Le stelle sulla bandiera indicavano gli obiettivi dichiarati del governo (e l&apos;unico legittimo all&apos;epoca in Iraq) del partito politico Baas: &quot;Unit\u00e0&quot;, &quot;Libert\u00e0&quot;, &quot;Socialismo&quot;.<\/p>\n<p style=\"text-align: justify\"><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3324\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_5.png\" width=\"500\" height=\"333\" alt=\"Bandiera dell&apos;Iraq-5\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"333\"><\/span><\/p>\n<p style=\"text-align: justify\">Nel 1991, la bandiera \u00e8 stata completata con un tackie (frase &quot;Allah Akbar!&quot;) Scritto da Honor del dittatore iracheno Saddam Hussein. Alla fine del rovesciamento di Hussein nel 2004, il Tabier inizi\u00f2 a essere scritto sulla bandiera di una buona lettera araba.<\/p>\n<p style=\"text-align: justify\"><span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3325\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_6.png\" width=\"500\" height=\"333\" alt=\"Bandiera dell&apos;Iraq-6\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"333\"><\/span> <span itemprop=\"image\" itemscope itemtype=\"https:\/\/schema.org\/ImageObject\"><img itemprop=\"url image\" loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3326\" src=\"\/wp-content\/uploads\/2021\/01\/flag-of-iraq_7.png\" width=\"500\" height=\"333\" alt=\"Bandiera dell&apos;Iraq-7\" \/><meta itemprop=\"width\" content=\"500\"><meta itemprop=\"height\" content=\"333\"><\/span><\/p>\n<p style=\"text-align: justify\">L&apos;ultima configurazione in questo giorno nella bandiera dell&apos;Iraq \u00e8 avvenuta nel 2008: la bandiera era priva di stelle verdi.<\/p>\n<h3 style=\"text-align: justify\">senza bandiera<\/h3>\n<p style=\"text-align: justify\">Alla fine del rovesciamento del regime dittatoriale di Saddam Hussein, c&apos;\u00e8 stata la proposta di prendere la bandiera, per nulla simile a nessun tessuto storico iracheno. \u00c8 stato sprecato da un panno bianco con 3 strisce strette nella parte inferiore (strisce di colore: blu, giallo, blu). Sul panno bianchissimo era raffigurata una mezzaluna zado-blu.<\/p>\n<p style=\"text-align: justify\">La Mezzaluna Blu su questa versione della bandiera irachena ha eseguito il segno dell&apos;Islam, due strisce blu: i Grandi Fiumi dell&apos;Iraq (Eufrate e Tigre) e la linea gialla &#8211; Civilt\u00e0 curda. Ma questa versione del segno di stato non ha ottenuto popolarit\u00e0 dagli arabi iracheni: era considerato molto simile a Israel Tricolor.<\/p>\n<h2 style=\"text-align: justify\">Descrizione bandiera dell&apos;Iraq<\/h2>\n<p style=\"text-align: justify\">L&apos;attuale bandiera dell&apos;Iraq, adottata nel 2008, si presenta come un tessuto a stampo rettangolare delle tre strisce orizzontali uguali. Le strisce dall&apos;alto verso il basso hanno i colori rosso, bianco e nero. Il centro della tela (sulla striscia bianca) raffigura la scritta &quot;Allahi Akbar!&quot;, Scritto non in caratteri piccoli con una buona lettera araba.<\/p>\n<h2 style=\"text-align: justify\">Significato dei colori e del segno della bandiera<\/h2>\n<p style=\"text-align: justify\">Il colore rosso della bandiera irachena &#8211; il simbolo della lotta contro i nemici dell&apos;Islam. Il bianco definisce la nobilt\u00e0 e la nobilt\u00e0 arabe. Nero: persone e paesi iracheni del passato. Colore verde, che sulla bandiera ha applicato la scritta &quot;Allahi Akbar!&quot;- non il brutto colore del mondo islamico.<\/p>\n<p style=\"text-align: justify\">C&apos;\u00e8 un&apos;altra interpretazione di questi personaggi e colori, secondo la quale il rosso \u00e8 considerato il colore della religione araba araba DOISLABLE, il bianco &#8211; il colore dell&apos;unit\u00e0 degli arabi di tutto il mondo, e il nero &#8211; il colore di il dolore dei caduti nelle battaglie.<\/p>\n<h2 style=\"text-align: justify\">Informazioni non specializzate sull&apos;Iraq<\/h2>\n<table>\n<tbody>\n<tr style=\"text-align: justify\">\n<td>Lingua ufficiale<\/td>\n<td>arabo e curdo<\/td>\n<\/tr>\n<tr style=\"text-align: justify\">\n<td>Capitale<\/td>\n<td>Baghdad<\/td>\n<\/tr>\n<tr style=\"text-align: justify\">\n<td>Territorio<\/td>\n<td>435 052 km2<\/td>\n<\/tr>\n<tr style=\"text-align: justify\">\n<td>Popolazione<\/td>\n<td>37 056 169 persone<\/td>\n<\/tr>\n<tr style=\"text-align: justify\">\n<td>Valuta<\/td>\n<td>Dinaro iracheno (IQD, codice 368)<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: justify\">Prefisso telefonico<\/td>\n<td style=\"text-align: justify\">+964<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Bandiera dell&apos;Iraq &#8211; uno dei principali segni di statualit\u00e0 di questo paese. La bandiera odierna della Repubblica irachena \u00e8 piuttosto giovane: \u00e8 stata adottata dal Parlamento del Paese&#8230;<\/p>\n","protected":false},"author":1,"featured_media":5854,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1562","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-bandiere-asia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/posts\/1562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/comments?post=1562"}],"version-history":[{"count":0,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/posts\/1562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/media\/5854"}],"wp:attachment":[{"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/media?parent=1562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/categories?post=1562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flags-world.com\/it\/wp-json\/wp\/v2\/tags?post=1562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}